{"id":9322,"date":"2024-07-10T20:22:21","date_gmt":"2024-07-10T20:22:21","guid":{"rendered":"https:\/\/curell.com\/?p=9322"},"modified":"2024-07-11T12:58:52","modified_gmt":"2024-07-11T12:58:52","slug":"la-patent-unitaria-comenca-amb-forca","status":"publish","type":"post","link":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/","title":{"rendered":"La Patent Unit\u00e0ria comen\u00e7a amb for\u00e7a"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #051a3f;color:#051a3f\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #051a3f;color:#051a3f\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/#Un_any_de_Patent_Unitaria\" >Un any de Patent Unit\u00e0ria\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/#Els_usuaris_espanyols_pugen_al_tren_a_primera_classe\" >Els usuaris espanyols pugen al tren a primera classe\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/#Lespanyol_idioma_tecnologic\" >L\u2019espanyol, idioma tecnol\u00f2gic\u00a0<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Un_any_de_Patent_Unitaria\"><\/span><span data-contrast=\"auto\">Un any de Patent Unit\u00e0ria<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span data-contrast=\"auto\">El passat 1 de juny de 2024 es va celebrar el primer any de la posada en funcionament de la Patent Unit\u00e0ria a Europa.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">La Patent Unit\u00e0ria \u00e9s el t\u00edtol de patent que proporciona protecci\u00f3 uniforme, amb un \u00fanic registre, a tots els pa\u00efsos de la Uni\u00f3 Europea que han signat i ratificat l\u2019anomenat \u201cPaquet de la Patent Unit\u00e0ria\u201d. Actualment, Alemanya, \u00c0ustria, B\u00e8lgica, Bulg\u00e0ria, Dinamarca, Eslov\u00e8nia, Est\u00f2nia, Finl\u00e0ndia, Fran\u00e7a, It\u00e0lia, Let\u00f2nia, Litu\u00e0nia, Luxemburg, Malta, Pa\u00efsos Baixos, Portugal i Su\u00e8cia constitueixen el grup de pa\u00efsos que ha participat de bon principi en el projecte. Malgrat tot, la resta de pa\u00efsos de la Uni\u00f3 Europea s\u2019hi poden anar afegint progressivament, com \u00e9s el cas de Romania que entrar\u00e0 en el sistema a partir de l\u20191 de setembre de 2024, engruixint a partir d\u2019aquesta data el territori protegit a 18 pa\u00efsos de la Uni\u00f3.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">En els Estats membres no participants en el sistema, b\u00e9 sigui perqu\u00e8 encara no han finalitzat el proc\u00e9s de ratificaci\u00f3 o perqu\u00e8, com en el cas d\u2019Espanya, no han signat els acords, la Patent Unit\u00e0ria no hi tindr\u00e0 efectes, de moment.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Malgrat tot, les dades des de la posada en marxa del sistema mostren que s\u2019han superat les expectatives inicials de tots el participants.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Segons dades publicades per l\u2019Oficina Europea de Patents (EPO), durant els primers 12 mesos de funcionament s\u2019han registrat m\u00e9s de 27.500 sol\u00b7licituds d\u2019efecte unitari davant l\u2019EPO, amb una proporci\u00f3 acumulada de gaireb\u00e9 un 20% de sol\u00b7licituds d\u2019efecte unitari, respecte del total de Patents Europees concedides, i a dia d\u2019avui ja s\u2019ha superat la xifra de 30.000 sol\u00b7licituds registrades. A m\u00e9s, aquesta proporci\u00f3 t\u00e9 una marcada tend\u00e8ncia creixent l\u2019any 2024 (24,3%), respecte de l\u2019any 2023 (17,5%).<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Els_usuaris_espanyols_pugen_al_tren_a_primera_classe\"><\/span><span data-contrast=\"auto\">Els usuaris espanyols pugen al tren a primera classe<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span data-contrast=\"auto\">D\u2019altra banda, \u00e9s important destacar que el pa\u00eds d\u2019origen del titular no condiciona la possibilitat de fer \u00fas del sistema unitari. Per exemple, tot i que Espanya no participa del sistema de cobertura, els titulars espanyols s\u00ed que en poden fer \u00fas per a protegir les seves invencions de manera unit\u00e0ria als pa\u00efsos participants. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Segons les estad\u00edstiques publicades per l\u2019EPO es pot deduir que hi ha un bon nivell de coneixement del sistema de la Patent Unit\u00e0ria per part dels titulars d\u2019origen espanyol. Passats 12 mesos de la posada en marxa del projecte, ja s\u2019han registrat 524 sol\u00b7licituds d\u2019efecte unitari de Patents Europees en les que el primer titular citat era d\u2019origen espanyol. D\u2019altra banda, de les 997 Patents Europees concedides l\u2019any 2023 a sol\u00b7licitants d\u2019origen espanyol es van derivar 350 sol\u00b7licituds d\u2019efecte unitari. Aix\u00ed, un 35% de sol\u00b7licituds d\u2019efecte unitari respecte del total de patents europees concedides fa que la proporci\u00f3 per part dels titulars espanyols sigui notablement superior a la mitjana Europea, per darrera de Pol\u00f2nia i Dinamarca amb un percentatge del 50%.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9311 size-full\" src=\"https:\/\/curell.com\/wp-content\/uploads\/2024\/07\/Captura-de-Pantalla-2024-07-10-a-les-22.15.52.png\" alt=\"\" width=\"573\" height=\"446\" srcset=\"https:\/\/curell.com\/wp-content\/uploads\/2024\/07\/Captura-de-Pantalla-2024-07-10-a-les-22.15.52.png 573w, https:\/\/curell.com\/wp-content\/uploads\/2024\/07\/Captura-de-Pantalla-2024-07-10-a-les-22.15.52-300x234.png 300w\" sizes=\"auto, (max-width: 573px) 100vw, 573px\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Font: <\/span><a href=\"https:\/\/www.epo.org\/en\/about-us\/statistics\/statistics-centre#\/unitary-patent\"><span data-contrast=\"none\">https:\/\/www.epo.org\/en\/about-us\/statistics\/statistics-centre#\/unitary-patent<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Lespanyol_idioma_tecnologic\"><\/span><span data-contrast=\"auto\">L\u2019espanyol, idioma tecnol\u00f2gic<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span data-contrast=\"auto\">Finalment, cal comentar que l\u2019espanyol s\u2019ha posicionat tamb\u00e9 com a llengua de refer\u00e8ncia en les sol\u00b7licituds d\u2019efecte unitari. Segons les dades de l\u2019EPO, amb un 30,1% l\u2019espanyol \u00e9s la primera llengua escollida pels titulars per a presentar la traducci\u00f3 obligat\u00f2ria que ha d\u2019acompanyar la sol\u00b7licitud d\u2019efecte unitari. Aquesta \u00e9s una gran not\u00edcia per a la divulgaci\u00f3 tecnol\u00f2gica a pa\u00efsos de parla hispana.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Aix\u00ed doncs, acabat el primer any de vida totes les dades apunten a que el projecte de la Patent Unit\u00e0ria avan\u00e7a amb pas ferm cap a la consolidaci\u00f3 com a una pe\u00e7a essencial del puzle de la construcci\u00f3 d\u2019Europa.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><strong>Autor<\/strong>: <a href=\"https:\/\/curell.com\/ca\/equipo\/nestor-corominas-macias\/\">N\u00e8stor Corominas<\/a>, soci de Curell Su\u00f1ol, SLP.<\/p>\n<p>Photo by Alexey Larionov on Unsplash.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un any de Patent Unit\u00e0ria\u00a0 El passat 1 de juny de 2024 es va celebrar el primer any de la posada en funcionament de la Patent Unit\u00e0ria a Europa.\u00a0\u00a0 La Patent Unit\u00e0ria \u00e9s el t\u00edtol de patent que proporciona protecci\u00f3 uniforme, amb un \u00fanic registre,&#8230;<\/p>\n","protected":false},"author":3,"featured_media":9314,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57,58,62,132],"tags":[],"class_list":["post-9322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualitat","category-articles-ca","category-destacades-actualitat","category-patents-i-models-dutilitat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Patent Unit\u00e0ria comen\u00e7a amb for\u00e7a | Curell Su\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Patent Unit\u00e0ria comen\u00e7a amb for\u00e7a | Curell Su\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"Un any de Patent Unit\u00e0ria\u00a0 El passat 1 de juny de 2024 es va celebrar el primer any de la posada en funcionament de la Patent Unit\u00e0ria a Europa.\u00a0\u00a0 La Patent Unit\u00e0ria \u00e9s el t\u00edtol de patent que proporciona protecci\u00f3 uniforme, amb un \u00fanic registre,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/\" \/>\n<meta property=\"og:site_name\" content=\"Curell Su\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-10T20:22:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-11T12:58:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/curell.com\/wp-content\/uploads\/2024\/07\/patente-unitaria-resumen.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"clarapirezcurell@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"clarapirezcurell@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/curell.com\\\/ca\\\/la-patent-unitaria-comenca-amb-forca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/curell.com\\\/ca\\\/la-patent-unitaria-comenca-amb-forca\\\/\"},\"author\":{\"name\":\"clarapirezcurell@gmail.com\",\"@id\":\"https:\\\/\\\/curell.com\\\/#\\\/schema\\\/person\\\/1c94ad2a17e2ed17aa5e510ba304ff87\"},\"headline\":\"La Patent Unit\u00e0ria comen\u00e7a amb for\u00e7a\",\"datePublished\":\"2024-07-10T20:22:21+00:00\",\"dateModified\":\"2024-07-11T12:58:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/curell.com\\\/ca\\\/la-patent-unitaria-comenca-amb-forca\\\/\"},\"wordCount\":673,\"publisher\":{\"@id\":\"https:\\\/\\\/curell.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/curell.com\\\/ca\\\/la-patent-unitaria-comenca-amb-forca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/curell.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/patente-unitaria-resumen.png\",\"articleSection\":[\"Actualitat\",\"Articles\",\"Destacades Actualitat\",\"Patents i models d'utilitat\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/curell.com\\\/ca\\\/la-patent-unitaria-comenca-amb-forca\\\/\",\"url\":\"https:\\\/\\\/curell.com\\\/ca\\\/la-patent-unitaria-comenca-amb-forca\\\/\",\"name\":\"La Patent Unit\u00e0ria comen\u00e7a amb for\u00e7a | Curell Su\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/curell.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/curell.com\\\/ca\\\/la-patent-unitaria-comenca-amb-forca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/curell.com\\\/ca\\\/la-patent-unitaria-comenca-amb-forca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/curell.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/patente-unitaria-resumen.png\",\"datePublished\":\"2024-07-10T20:22:21+00:00\",\"dateModified\":\"2024-07-11T12:58:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/curell.com\\\/ca\\\/la-patent-unitaria-comenca-amb-forca\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/curell.com\\\/ca\\\/la-patent-unitaria-comenca-amb-forca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/curell.com\\\/ca\\\/la-patent-unitaria-comenca-amb-forca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/curell.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/patente-unitaria-resumen.png\",\"contentUrl\":\"https:\\\/\\\/curell.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/patente-unitaria-resumen.png\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/curell.com\\\/ca\\\/la-patent-unitaria-comenca-amb-forca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/curell.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Patent Unit\u00e0ria comen\u00e7a amb for\u00e7a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/curell.com\\\/#website\",\"url\":\"https:\\\/\\\/curell.com\\\/\",\"name\":\"Curell Su\u00f1ol\",\"description\":\"Patentes, Marcas y Dise\u00f1os desde 1946\",\"publisher\":{\"@id\":\"https:\\\/\\\/curell.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/curell.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/curell.com\\\/#organization\",\"name\":\"Curell Su\u00f1ol\",\"url\":\"https:\\\/\\\/curell.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/curell.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/curell.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/curell-3.png\",\"contentUrl\":\"https:\\\/\\\/curell.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/curell-3.png\",\"width\":300,\"height\":70,\"caption\":\"Curell Su\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/curell.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es.linkedin.com\\\/company\\\/curell-su-ol\",\"https:\\\/\\\/www.instagram.com\\\/curell.sunol\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/curell.com\\\/#\\\/schema\\\/person\\\/1c94ad2a17e2ed17aa5e510ba304ff87\",\"name\":\"clarapirezcurell@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ba768f4c1f2dc029882cc058466e728a2fb044efeb07308ce14b58859479d16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ba768f4c1f2dc029882cc058466e728a2fb044efeb07308ce14b58859479d16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ba768f4c1f2dc029882cc058466e728a2fb044efeb07308ce14b58859479d16?s=96&d=mm&r=g\",\"caption\":\"clarapirezcurell@gmail.com\"},\"url\":\"#\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Patent Unit\u00e0ria comen\u00e7a amb for\u00e7a | Curell Su\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/","og_locale":"ca_ES","og_type":"article","og_title":"La Patent Unit\u00e0ria comen\u00e7a amb for\u00e7a | Curell Su\u00f1ol","og_description":"Un any de Patent Unit\u00e0ria\u00a0 El passat 1 de juny de 2024 es va celebrar el primer any de la posada en funcionament de la Patent Unit\u00e0ria a Europa.\u00a0\u00a0 La Patent Unit\u00e0ria \u00e9s el t\u00edtol de patent que proporciona protecci\u00f3 uniforme, amb un \u00fanic registre,...","og_url":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/","og_site_name":"Curell Su\u00f1ol","article_published_time":"2024-07-10T20:22:21+00:00","article_modified_time":"2024-07-11T12:58:52+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/curell.com\/wp-content\/uploads\/2024\/07\/patente-unitaria-resumen.png","type":"image\/png"}],"author":"clarapirezcurell@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"clarapirezcurell@gmail.com","Temps estimat de lectura":"4 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/#article","isPartOf":{"@id":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/"},"author":{"name":"clarapirezcurell@gmail.com","@id":"https:\/\/curell.com\/#\/schema\/person\/1c94ad2a17e2ed17aa5e510ba304ff87"},"headline":"La Patent Unit\u00e0ria comen\u00e7a amb for\u00e7a","datePublished":"2024-07-10T20:22:21+00:00","dateModified":"2024-07-11T12:58:52+00:00","mainEntityOfPage":{"@id":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/"},"wordCount":673,"publisher":{"@id":"https:\/\/curell.com\/#organization"},"image":{"@id":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/#primaryimage"},"thumbnailUrl":"https:\/\/curell.com\/wp-content\/uploads\/2024\/07\/patente-unitaria-resumen.png","articleSection":["Actualitat","Articles","Destacades Actualitat","Patents i models d'utilitat"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/","url":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/","name":"La Patent Unit\u00e0ria comen\u00e7a amb for\u00e7a | Curell Su\u00f1ol","isPartOf":{"@id":"https:\/\/curell.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/#primaryimage"},"image":{"@id":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/#primaryimage"},"thumbnailUrl":"https:\/\/curell.com\/wp-content\/uploads\/2024\/07\/patente-unitaria-resumen.png","datePublished":"2024-07-10T20:22:21+00:00","dateModified":"2024-07-11T12:58:52+00:00","breadcrumb":{"@id":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/#primaryimage","url":"https:\/\/curell.com\/wp-content\/uploads\/2024\/07\/patente-unitaria-resumen.png","contentUrl":"https:\/\/curell.com\/wp-content\/uploads\/2024\/07\/patente-unitaria-resumen.png","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/curell.com\/ca\/la-patent-unitaria-comenca-amb-forca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/curell.com\/ca\/"},{"@type":"ListItem","position":2,"name":"La Patent Unit\u00e0ria comen\u00e7a amb for\u00e7a"}]},{"@type":"WebSite","@id":"https:\/\/curell.com\/#website","url":"https:\/\/curell.com\/","name":"Curell Su\u00f1ol","description":"Patentes, Marcas y Dise\u00f1os desde 1946","publisher":{"@id":"https:\/\/curell.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/curell.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/curell.com\/#organization","name":"Curell Su\u00f1ol","url":"https:\/\/curell.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/curell.com\/#\/schema\/logo\/image\/","url":"https:\/\/curell.com\/wp-content\/uploads\/2022\/10\/curell-3.png","contentUrl":"https:\/\/curell.com\/wp-content\/uploads\/2022\/10\/curell-3.png","width":300,"height":70,"caption":"Curell Su\u00f1ol"},"image":{"@id":"https:\/\/curell.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es.linkedin.com\/company\/curell-su-ol","https:\/\/www.instagram.com\/curell.sunol\/"]},{"@type":"Person","@id":"https:\/\/curell.com\/#\/schema\/person\/1c94ad2a17e2ed17aa5e510ba304ff87","name":"clarapirezcurell@gmail.com","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/5ba768f4c1f2dc029882cc058466e728a2fb044efeb07308ce14b58859479d16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ba768f4c1f2dc029882cc058466e728a2fb044efeb07308ce14b58859479d16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ba768f4c1f2dc029882cc058466e728a2fb044efeb07308ce14b58859479d16?s=96&d=mm&r=g","caption":"clarapirezcurell@gmail.com"},"url":"#"}]}},"_links":{"self":[{"href":"https:\/\/curell.com\/ca\/wp-json\/wp\/v2\/posts\/9322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/curell.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/curell.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/curell.com\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/curell.com\/ca\/wp-json\/wp\/v2\/comments?post=9322"}],"version-history":[{"count":1,"href":"https:\/\/curell.com\/ca\/wp-json\/wp\/v2\/posts\/9322\/revisions"}],"predecessor-version":[{"id":9325,"href":"https:\/\/curell.com\/ca\/wp-json\/wp\/v2\/posts\/9322\/revisions\/9325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/curell.com\/ca\/wp-json\/wp\/v2\/media\/9314"}],"wp:attachment":[{"href":"https:\/\/curell.com\/ca\/wp-json\/wp\/v2\/media?parent=9322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/curell.com\/ca\/wp-json\/wp\/v2\/categories?post=9322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/curell.com\/ca\/wp-json\/wp\/v2\/tags?post=9322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}